{"id":77168,"date":"2026-05-12T18:03:00","date_gmt":"2026-05-13T00:03:00","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2026\/05\/12\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/"},"modified":"2026-05-12T18:35:09","modified_gmt":"2026-05-13T00:35:09","slug":"cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2026\/05\/12\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/","title":{"rendered":"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p>La vocera de la Agencia Central de Inteligencia (CIA) estadunidense, Liz Lyons, calific\u00f3 este martes como \u201cinformaci\u00f3n falsa y sensacionalista\u201d el reporte de CNN que afirma que la agencia habr\u00eda participado en una operaci\u00f3n encubierta en M\u00e9xico que termin\u00f3 con la muerte de un operador del c\u00e1rtel de Sinaloa.<\/p>\n\n\n\n<p>\u201cSe trata de informaci\u00f3n falsa y sensacionalista que no sirve m\u00e1s que como campa\u00f1a de relaciones p\u00fablicas para los c\u00e1rteles y pone en riesgo la vida de los estadunidenses\u201d, escribi\u00f3 Lyons en redes sociales, y con la captura de pantalla a la publicaci\u00f3n de CNN.<\/p>\n\n\n\n<p>El reportaje de la cadena estadunidense sostiene que Francisco Beltr\u00e1n, \u201cEl Pay\u00edn\u201d no muri\u00f3 en un accidente, sino en un asesinato \u201cfacilitado\u201d por la CIA mediante una operaci\u00f3n realizada a finales de marzo en el Estado de M\u00e9xico, cerca del Aeropuerto Internacional Felipe \u00c1ngeles.<\/p>\n\n\n\n<p>Seg\u00fan CNN, el veh\u00edculo en el que viajaba Beltr\u00e1n explot\u00f3, causando tambi\u00e9n la muerte de su chofer. Las versiones preliminares apuntaban a una detonaci\u00f3n accidental mientras transportaban un artefacto explosivo, pero el medio asegur\u00f3 posteriormente que el dispositivo habr\u00eda sido colocado deliberadamente en el autom\u00f3vil, citando informaci\u00f3n atribuida a la fiscal\u00eda mexiquense.<\/p>\n\n\n\n<p>La publicaci\u00f3n relaciona el caso con la estrategia impulsada por el gobierno del presidente Donald Trump contra organizaciones criminales mexicanas y se\u00f1ala que el reporte ha intensificado el debate sobre posibles operaciones directas estadunidenses en territorio mexicano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vocera de la Agencia Central de Inteligencia (CIA) estadunidense, Liz Lyons, calific\u00f3 este martes como \u201cinformaci\u00f3n falsa y sensacionalista\u201d el reporte de CNN que afirma que la agencia habr\u00eda participado en una operaci\u00f3n encubierta en M\u00e9xico que termin\u00f3 con la muerte de un operador del c\u00e1rtel de Sinaloa. \u201cSe trata de informaci\u00f3n falsa y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":77170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,19],"tags":[],"class_list":{"0":"post-77168","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-oaxaca","8":"category-nacional"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa - LA BRAVA RADIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"La vocera de la Agencia Central de Inteligencia (CIA) estadunidense, Liz Lyons, calific\u00f3 este martes como \u201cinformaci\u00f3n falsa y sensacionalista\u201d el reporte de CNN que afirma que la agencia habr\u00eda participado en una operaci\u00f3n encubierta en M\u00e9xico que termin\u00f3 con la muerte de un operador del c\u00e1rtel de Sinaloa. \u201cSe trata de informaci\u00f3n falsa y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T00:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2026\/05\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1142\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Agencias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agencias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2026\\\/05\\\/12\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/\"},\"author\":{\"name\":\"Agencias\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c58e20e655cea90f69f1c6eec40f7d8c\"},\"headline\":\"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa\",\"datePublished\":\"2026-05-13T00:03:00+00:00\",\"dateModified\":\"2026-05-13T00:35:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2026\\\/05\\\/12\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/\"},\"wordCount\":269,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp\",\"articleSection\":[\"LOCAL\",\"NACIONAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2026\\\/05\\\/12\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/\",\"name\":\"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp\",\"datePublished\":\"2026-05-13T00:03:00+00:00\",\"dateModified\":\"2026-05-13T00:35:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c58e20e655cea90f69f1c6eec40f7d8c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp\",\"width\":1200,\"height\":1142},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c58e20e655cea90f69f1c6eec40f7d8c\",\"name\":\"Agencias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/739e0b61adf9e398b425c36718c8752286da0e8cd90f20ce9a86678abc26aa0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/739e0b61adf9e398b425c36718c8752286da0e8cd90f20ce9a86678abc26aa0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/739e0b61adf9e398b425c36718c8752286da0e8cd90f20ce9a86678abc26aa0d?s=96&d=mm&r=g\",\"caption\":\"Agencias\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/agencias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa - LA BRAVA RADIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/","og_locale":"es_MX","og_type":"article","og_title":"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa - LA BRAVA RADIO","og_description":"La vocera de la Agencia Central de Inteligencia (CIA) estadunidense, Liz Lyons, calific\u00f3 este martes como \u201cinformaci\u00f3n falsa y sensacionalista\u201d el reporte de CNN que afirma que la agencia habr\u00eda participado en una operaci\u00f3n encubierta en M\u00e9xico que termin\u00f3 con la muerte de un operador del c\u00e1rtel de Sinaloa. \u201cSe trata de informaci\u00f3n falsa y [&hellip;]","og_url":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2026-05-13T00:03:00+00:00","article_modified_time":"2026-05-13T00:35:09+00:00","og_image":[{"width":1200,"height":1142,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2026\/05\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp","type":"image\/webp"}],"author":"Agencias","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agencias","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2026\/05\/12\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/"},"author":{"name":"Agencias","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c58e20e655cea90f69f1c6eec40f7d8c"},"headline":"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa","datePublished":"2026-05-13T00:03:00+00:00","dateModified":"2026-05-13T00:35:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2026\/05\/12\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/"},"wordCount":269,"image":{"@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2026\/05\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp","articleSection":["LOCAL","NACIONAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2026\/05\/12\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/","url":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/","name":"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2026\/05\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp","datePublished":"2026-05-13T00:03:00+00:00","dateModified":"2026-05-13T00:35:09+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c58e20e655cea90f69f1c6eec40f7d8c"},"breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2026\/05\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2026\/05\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa.webp","width":1200,"height":1142},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/cia-rechaza-reporte-de-cnn-sobre-presunta-operacion-contra-operador-del-cartel-de-sinaloa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"CIA rechaza reporte de CNN sobre presunta operaci\u00f3n contra operador del c\u00e1rtel de Sinaloa"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c58e20e655cea90f69f1c6eec40f7d8c","name":"Agencias","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/739e0b61adf9e398b425c36718c8752286da0e8cd90f20ce9a86678abc26aa0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/739e0b61adf9e398b425c36718c8752286da0e8cd90f20ce9a86678abc26aa0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/739e0b61adf9e398b425c36718c8752286da0e8cd90f20ce9a86678abc26aa0d?s=96&d=mm&r=g","caption":"Agencias"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/agencias\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/77168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=77168"}],"version-history":[{"count":1,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/77168\/revisions"}],"predecessor-version":[{"id":77169,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/77168\/revisions\/77169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/77170"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=77168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=77168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=77168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}