{"id":3083,"date":"2021-10-04T20:55:28","date_gmt":"2021-10-05T01:55:28","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?p=3083"},"modified":"2021-10-04T20:55:29","modified_gmt":"2021-10-05T01:55:29","slug":"difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/","title":{"rendered":"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax<\/strong>. La Casa de la Cultura Oaxaque\u00f1a (CCO) difunde el trabajo art\u00edstico de Alfonso Barrera, quien actualmente exhibe su exposici\u00f3n \u201cLa felicidad es una ola poderosa\u201d en NN Galer\u00eda ubicada en Privada Aldama #110, en el Barrio de Jalatlaco de la capital oaxaque\u00f1a.<\/p>\n\n\n\n<p>Esta exposici\u00f3n integrada de 50 piezas, es la exhibici\u00f3n m\u00e1s grande que el artista ha reunido, pues se complementa a trav\u00e9s de la exploraci\u00f3n de diversas t\u00e9cnicas como el dibujo, acr\u00edlico, la tinta, \u00f3leo, cer\u00e1mica y serigraf\u00eda. \u201cToda la obra fue creada a lo largo de 10 meses\u201d, cuenta Alfonso Barrera para la CCO.<\/p>\n\n\n\n<p>Inari Res\u00e9ndiz, escritora del texto de sala para esta exposici\u00f3n, considera que \u201cLa felicidad es una ola poderosa\u201d expresa prematuramente parte del inconsciente de Alfonso Barrera y, a su vez, una idea clara del periodo actual que atraviesan sus procesos creativos.<\/p>\n\n\n\n<p>\u201cMuchas de las im\u00e1genes que encontraremos en esta muestra ser\u00e1n ejemplo de ello. Formulaciones intuitivas se dibujan y aparecen desde lo no concreto: mujeres nadadoras, mujeres pochote, animales trascendiendo su naturaleza, citas y referencias importantes que evidencian su bagaje como artista\u201d.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que \u201ceste universo es representado con una paleta de color vibrante y probablemente nueva en su obra, s\u00edntoma de su presente. El artista nos traslada a un espacio de fantas\u00eda donde el reto es abandonar la necesidad de atrapar alg\u00fan sentido\u201d.<\/p>\n\n\n\n<p>Alfonso Barrera Mu\u00f1iz es un artista pl\u00e1stico nacido en el Estado de M\u00e9xico y radicado en la ciudad de Oaxaca. Su trabajo incluye el dibujo, la pintura, el objeto y la publicaci\u00f3n a partir de situaciones cotidianas, aborda el simbolismo de los objetos representados en atm\u00f3sferas on\u00edricas.<\/p>\n\n\n\n<p>Su obra ha sido expuesta en M\u00e9xico, Estados Unidos, Europa y Jap\u00f3n. Actualmente desarrolla publicaciones independientes con su proyecto editorial Polvoh Press.<\/p>\n\n\n\n<p>La exposici\u00f3n \u201cLa felicidad es una ola poderosa\u201d estar\u00e1 abierta al p\u00fablico hasta el 12 de octubre en NN Galer\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. La Casa de la Cultura Oaxaque\u00f1a (CCO) difunde el trabajo art\u00edstico de Alfonso Barrera, quien actualmente exhibe su exposici\u00f3n \u201cLa felicidad es una ola poderosa\u201d en NN Galer\u00eda ubicada en Privada Aldama #110, en el Barrio de Jalatlaco de la capital oaxaque\u00f1a. Esta exposici\u00f3n integrada de 50 piezas, es la exhibici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-3083","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-oaxaca"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera - LA BRAVA RADIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"Oaxaca de Ju\u00e1rez, Oax. La Casa de la Cultura Oaxaque\u00f1a (CCO) difunde el trabajo art\u00edstico de Alfonso Barrera, quien actualmente exhibe su exposici\u00f3n \u201cLa felicidad es una ola poderosa\u201d en NN Galer\u00eda ubicada en Privada Aldama #110, en el Barrio de Jalatlaco de la capital oaxaque\u00f1a. Esta exposici\u00f3n integrada de 50 piezas, es la exhibici\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-05T01:55:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-05T01:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/10\/La-felicidad-es-una-ola-poderosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2020\" \/>\n\t<meta property=\"og:image:height\" content=\"1617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/\"},\"author\":{\"name\":\"Staff\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\"},\"headline\":\"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera\",\"datePublished\":\"2021-10-05T01:55:28+00:00\",\"dateModified\":\"2021-10-05T01:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/\"},\"wordCount\":355,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/La-felicidad-es-una-ola-poderosa.jpg\",\"articleSection\":[\"LOCAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/\",\"name\":\"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/La-felicidad-es-una-ola-poderosa.jpg\",\"datePublished\":\"2021-10-05T01:55:28+00:00\",\"dateModified\":\"2021-10-05T01:55:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/La-felicidad-es-una-ola-poderosa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/10\\\/La-felicidad-es-una-ola-poderosa.jpg\",\"width\":2020,\"height\":1617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/10\\\/04\\\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\",\"name\":\"Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"caption\":\"Staff\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera - LA BRAVA RADIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/","og_locale":"es_MX","og_type":"article","og_title":"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera - LA BRAVA RADIO","og_description":"Oaxaca de Ju\u00e1rez, Oax. La Casa de la Cultura Oaxaque\u00f1a (CCO) difunde el trabajo art\u00edstico de Alfonso Barrera, quien actualmente exhibe su exposici\u00f3n \u201cLa felicidad es una ola poderosa\u201d en NN Galer\u00eda ubicada en Privada Aldama #110, en el Barrio de Jalatlaco de la capital oaxaque\u00f1a. Esta exposici\u00f3n integrada de 50 piezas, es la exhibici\u00f3n [&hellip;]","og_url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2021-10-05T01:55:28+00:00","article_modified_time":"2021-10-05T01:55:29+00:00","og_image":[{"width":2020,"height":1617,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/10\/La-felicidad-es-una-ola-poderosa.jpg","type":"image\/jpeg"}],"author":"Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Staff","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/"},"author":{"name":"Staff","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7"},"headline":"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera","datePublished":"2021-10-05T01:55:28+00:00","dateModified":"2021-10-05T01:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/"},"wordCount":355,"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/10\/La-felicidad-es-una-ola-poderosa.jpg","articleSection":["LOCAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/","name":"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/10\/La-felicidad-es-una-ola-poderosa.jpg","datePublished":"2021-10-05T01:55:28+00:00","dateModified":"2021-10-05T01:55:29+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7"},"breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/10\/La-felicidad-es-una-ola-poderosa.jpg","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/10\/La-felicidad-es-una-ola-poderosa.jpg","width":2020,"height":1617},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/10\/04\/difunde-la-cco-la-felicidad-es-una-ola-poderosa-de-alfonso-barrera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"Difunde la CCO \u201cLa felicidad es una ola poderosa\u201d de Alfonso Barrera"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7","name":"Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","caption":"Staff"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/3083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=3083"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/3083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/3084"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=3083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=3083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=3083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}