{"id":2841,"date":"2021-09-30T10:17:18","date_gmt":"2021-09-30T15:17:18","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?p=2841"},"modified":"2021-09-30T10:17:19","modified_gmt":"2021-09-30T15:17:19","slug":"concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/","title":{"rendered":"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p><strong>Tlalixtac de Cabrera, Oax. <\/strong>La Secretar\u00eda General de Gobierno (Segego), a trav\u00e9s de la Subsecretar\u00eda de Fortalecimiento Municipal, junto con la Coordinaci\u00f3n General de Atenci\u00f3n Regional (Cgar), instalaron una mesa de di\u00e1logo con autoridades del municipio de Chalcatongo de Hidalgo y representantes de la agencia de polic\u00eda Independencia.<\/p>\n\n\n\n<p>Con la instrucci\u00f3n del secretario general de Gobierno (Segego), Francisco Javier Garc\u00eda L\u00f3pez, el subsecretario de Fortalecimiento Municipal, Mart\u00edn Vela Gil, instal\u00f3 una mesa de di\u00e1logo junto con Edith Aparicio Mart\u00ednez y Rolando Cruz Sampedro, delegados de atenci\u00f3n regional de Tlaxiaco y Nochixtl\u00e1n, con el objetivo de conciliar el conflicto derivado de la distribuci\u00f3n de recursos de los ramos 28 y 33 por parte del municipio de Chalcatongo de Hidalgo a la agencia de polic\u00eda Independencia.<\/p>\n\n\n\n<p>En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33 fondo III del ejercicio fiscal 2021, as\u00ed mismo, la ciudadana Patrocinia Jim\u00e9nez Jim\u00e9nez, expuso que como vecina de la agencia de polic\u00eda en la actualidad algunos sectores de la poblaci\u00f3n no pueden acceder al agua potable.<\/p>\n\n\n\n<p>Al finalizar la mesa de di\u00e1logo se firm\u00f3 una minuta en la que se acuerda que el pr\u00f3ximo 4 de octubre en la agencia de polic\u00eda Independencia, se realizar\u00e1 una mesa de trabajo entre los quejosos de la reconexi\u00f3n del agua potable, el agente de polic\u00eda, una representaci\u00f3n del Ayuntamiento de Chalcatongo de Hidalgo y de las dependencias gubernamentales para resolver dicha problem\u00e1tica, posteriormente se ratificar\u00e1 el inicio de los trabajos de la obra de electrificaci\u00f3n correspondiente al ramo 33, fondo III, que ha solicitado la agencia de polic\u00eda.<\/p>\n\n\n\n<p>Con relaci\u00f3n al ramo 28 del presente ejercicio fiscal, el ayuntamiento de Chalcatongo de Hidalgo, se compromete a entregar a la agencia de polic\u00eda de Independencia la cantidad de 7 mil pesos de forma mensual, manteniendo el incremento de 2 mil pesos que se acord\u00f3 a partir del mes de mayo del a\u00f1o en curso.<\/p>\n\n\n\n<p>En ese sentido, la agencia de polic\u00eda Independencia, se compromete a realizar la comprobaci\u00f3n al Ayuntamiento de los gastos correspondientes a los meses de enero a mayo, y posteriormente se les entregar\u00e1 lo correspondiente a los meses de junio, julio, agosto y septiembre, la cantidad que ha sido pactada.<\/p>\n\n\n\n<p>As\u00ed mismo, las partes se comprometen a respetar la minuta de acuerdos y mantener el respeto, la paz y cordialidad.<\/p>\n\n\n\n<p>En la mesa de di\u00e1logo participaron por parte del municipio de Chalcatongo de Hidalgo, el presidente municipal, Adolfo Nicol\u00e1s Nicol\u00e1s; la s\u00edndica municipal, Wendy Cort\u00e9s Ruiz; la regidora de obras, Sabina Adela L\u00f3pez Cort\u00e9s y la ciudadana Patrocinia Jim\u00e9nez Jim\u00e9nez.<\/p>\n\n\n\n<p>Por parte de la agencia de polic\u00eda Independencia, el agente de polic\u00eda, Primitivo Jim\u00e9nez Cort\u00e9s; Diana L\u00f3pez Cort\u00e9s, Salom\u00f3n Soria Ruiz, Elvia Ram\u00edrez Jim\u00e9nez y Ver\u00f3nica Miquel Mendoza.<\/p>\n\n\n\n<p>La Segego exhorta a las y los presidentes de los 570 municipios, a cumplir con sus agencias en cuanto a la asignaci\u00f3n y ministraci\u00f3n de recursos federales; asimismo, se hace un llamado a las y los habitantes de los municipios y agencias, a conducirse con civilidad, privilegiar el di\u00e1logo para alcanzar acuerdos que beneficien a las comunidades y no afectar a terceros con bloqueos carreteros o realizar la retenci\u00f3n de personas, toda vez que estas acciones no abonan a la paz en el estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tlalixtac de Cabrera, Oax. La Secretar\u00eda General de Gobierno (Segego), a trav\u00e9s de la Subsecretar\u00eda de Fortalecimiento Municipal, junto con la Coordinaci\u00f3n General de Atenci\u00f3n Regional (Cgar), instalaron una mesa de di\u00e1logo con autoridades del municipio de Chalcatongo de Hidalgo y representantes de la agencia de polic\u00eda Independencia. Con la instrucci\u00f3n del secretario general de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-2841","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-oaxaca"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia - LA BRAVA RADIO<\/title>\n<meta name=\"description\" content=\"En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T15:17:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T15:17:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local30092021-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1156\" \/>\n\t<meta property=\"og:image:height\" content=\"868\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/\"},\"author\":{\"name\":\"Staff\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\"},\"headline\":\"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia\",\"datePublished\":\"2021-09-30T15:17:18+00:00\",\"dateModified\":\"2021-09-30T15:17:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/\"},\"wordCount\":613,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local30092021-5.jpg\",\"articleSection\":[\"LOCAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/\",\"name\":\"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local30092021-5.jpg\",\"datePublished\":\"2021-09-30T15:17:18+00:00\",\"dateModified\":\"2021-09-30T15:17:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\"},\"description\":\"En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local30092021-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local30092021-5.jpg\",\"width\":1156,\"height\":868},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\",\"name\":\"Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"caption\":\"Staff\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia - LA BRAVA RADIO","description":"En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/","og_locale":"es_MX","og_type":"article","og_title":"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia - LA BRAVA RADIO","og_description":"En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33","og_url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2021-09-30T15:17:18+00:00","article_modified_time":"2021-09-30T15:17:19+00:00","og_image":[{"width":1156,"height":868,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local30092021-5.jpg","type":"image\/jpeg"}],"author":"Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Staff","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/"},"author":{"name":"Staff","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7"},"headline":"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia","datePublished":"2021-09-30T15:17:18+00:00","dateModified":"2021-09-30T15:17:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/"},"wordCount":613,"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local30092021-5.jpg","articleSection":["LOCAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/","name":"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local30092021-5.jpg","datePublished":"2021-09-30T15:17:18+00:00","dateModified":"2021-09-30T15:17:19+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7"},"description":"En ese sentido, la agencia de polic\u00eda Independencia, solicita la entrega de sus recursos asignados del ramo 28 y ramo 33","breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local30092021-5.jpg","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local30092021-5.jpg","width":1156,"height":868},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/concilia-segego-y-cgar-conflicto-entre-el-municipio-de-chalcatongo-de-hidalgo-y-su-agencia-de-policia-independencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"Concilia Segego y Cgar conflicto entre el municipio de Chalcatongo de Hidalgo y su agencia de polic\u00eda Independencia"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7","name":"Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","caption":"Staff"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=2841"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/2844"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=2841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=2841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=2841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}