{"id":2840,"date":"2021-09-30T10:15:39","date_gmt":"2021-09-30T15:15:39","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?p=2840"},"modified":"2021-09-30T10:15:40","modified_gmt":"2021-09-30T15:15:40","slug":"antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/","title":{"rendered":"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su  Segundo Festival Internacional"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p><strong>Antequera, M\u00e1laga.- <\/strong>Una de las ciudades con mucho carisma en M\u00e1laga es Antequera donde su belleza arquitect\u00f3nica es parte de sus atractivos para visitarla, sin embargo tambi\u00e9n un pretexto es ir a escuchar \u00f3rganos hist\u00f3ricos que se encuentran en diferentes edificios.<\/p>\n\n\n\n<p>Jes\u00fas Sampedro, director del Festival Internacional de \u00d3rgano de Antequera, nos explic\u00f3 que el festival ha presentado a&nbsp; tres maestros de diferentes nacionalidades: Polonia, Francia e Italia.<\/p>\n\n\n\n<p>Los tres ejecutaron su programa en el \u00f3rgano hist\u00f3rico del siglo XVIII que se encuentra en la Iglesia Colegiata de San Sebasti\u00e1n.<\/p>\n\n\n\n<p>\u201cEste es un \u00f3rgano barroco espa\u00f1ol, se distingue por su&nbsp; trompeter\u00eda de batalla que sobresale de la caja musical. Es originario de Espa\u00f1a este tipo de instrumentos, si hay en otros lados, es una copia inspirada de&nbsp; Espa\u00f1a. Este \u00f3rgano es del siglo XVII. Y se conoce como trompeta de batalla,&nbsp; porque se utilizaba para una obra musical que se llamaba batalla. Adem\u00e1s era&nbsp; para sonorizar la misa\u201d, explica Sampedro.<\/p>\n\n\n\n<p>Destaca que este tipo de&nbsp; \u00f3rganos son conocidos en M\u00e9xico y existen algunos.<\/p>\n\n\n\n<p>El que se utiliz\u00f3 para este Festival de \u00f3rgano se restaur\u00f3 gracias a un programa de Andaluc\u00eda Barroca en el a\u00f1o 2000.<\/p>\n\n\n\n<p>Sampedro destaca que este instrumento : &#8220;Lo restaur\u00f3 un organero alem\u00e1n, quien aprovech\u00f3 la caja que es barroca de 1782 y los tubos. Un organero de Cuenca llamado, Tom\u00e1s de In\u00e9s Ortega,&nbsp; en 1803, termin\u00f3 el&nbsp; \u00f3rgano, formando equipo con&nbsp; Juli\u00e1n de la Orden&nbsp; que fue el maestro quien hizo el \u00f3rgano de la Catedral de M\u00e1laga de 1780 que&nbsp; son dos instrumentos gemelos\u201d .<\/p>\n\n\n\n<p>El poder realizar un festival de \u00f3rgano&nbsp; tiene importancia para preservar el inter\u00e9s del p\u00fablico por escuchar estos instrumentos hist\u00f3ricos. Adem\u00e1s que se da&nbsp; mantenimiento.&nbsp;<\/p>\n\n\n\n<p>Durante el festival siempre viene un organero para afinar, el&nbsp; proceso es caro, porque debe tenerse mucho cuidado con el instrumento que tiene m\u00e1s de 250 a\u00f1os. Si se revisa cada a\u00f1o el instrumento se encuentra en perfectas condiciones -explica el director- el \u00f3rgano que se utiliz\u00f3 para el festival tiene muchos mecanismos que son de 1803 igual&nbsp; que los de la catedral de M\u00e1laga.&nbsp;<\/p>\n\n\n\n<p>Es importante se\u00f1alar que no cualquier organista puede tocar un instrumento de est\u00e1 categor\u00eda, debido a que cada uno tiene un sistema diferente.<\/p>\n\n\n\n<p>\u201cDeseamos que el p\u00fablico se acerque a la m\u00fasica de \u00f3rgano y sobre todo en Antequera debido que &nbsp; tenemos quince instrumentos hist\u00f3ricos del siglo XVIII, y de est\u00e1 forma&nbsp; presionamos para que se pueda recuperar el patrimonio de est\u00e1&nbsp; ciudad que realmente es la ciudad de los \u00f3rganos, ya que no conozco otra que en tan poco espacio haya tanto \u00f3rgano&nbsp; hist\u00f3rico adem\u00e1s que&nbsp; es un reclamo tur\u00edstico y cultural\u201d.<\/p>\n\n\n\n<p>El festival termin\u00f3 exitosamente con el&nbsp; maestro Luigi Ratti, italiano, deleit\u00f3 a los asistentes con temas como: Alessandro Scarlatti (1660-1725) <em>Toccata aperta d\u2019organo<\/em>, Bernardo Pasquini (1637-1710) <em>Variazioni sopra il Paggio Todesco<\/em>, Arcangelo Corelli (1653-1713) <em>Concerto Grosso op 6 n 10 in do maggiore Preludio Allemanda, Adagio, Corrente, Allegro, Minuetto Appropriati all\u2019organo da Thoma s Billington<\/em>, Domenico Zipoli (1688-1726) <em>Canzona in sol minore<\/em>, Domenico Puccini (1772-1815) <em>Sonata 27,<\/em>Gherardo Gherardeschi (1835-1905)<em> Adagio per la comunione <\/em>y Giacomo Puccini (1858-1924)&nbsp; <em>Marcia in sol maggiore<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antequera, M\u00e1laga.- Una de las ciudades con mucho carisma en M\u00e1laga es Antequera donde su belleza arquitect\u00f3nica es parte de sus atractivos para visitarla, sin embargo tambi\u00e9n un pretexto es ir a escuchar \u00f3rganos hist\u00f3ricos que se encuentran en diferentes edificios. Jes\u00fas Sampedro, director del Festival Internacional de \u00d3rgano de Antequera, nos explic\u00f3 que el [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-2840","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sin-categoria"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional - LA BRAVA RADIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"Antequera, M\u00e1laga.- Una de las ciudades con mucho carisma en M\u00e1laga es Antequera donde su belleza arquitect\u00f3nica es parte de sus atractivos para visitarla, sin embargo tambi\u00e9n un pretexto es ir a escuchar \u00f3rganos hist\u00f3ricos que se encuentran en diferentes edificios. Jes\u00fas Sampedro, director del Festival Internacional de \u00d3rgano de Antequera, nos explic\u00f3 que el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T15:15:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T15:15:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/Espectaculos1-30.09.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/\"},\"author\":{\"name\":\"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/6efbef67fc52e8e1456e88c1d9e31185\"},\"headline\":\"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional\",\"datePublished\":\"2021-09-30T15:15:39+00:00\",\"dateModified\":\"2021-09-30T15:15:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/\"},\"wordCount\":591,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/Espectaculos1-30.09.21.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/\",\"name\":\"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/Espectaculos1-30.09.21.jpg\",\"datePublished\":\"2021-09-30T15:15:39+00:00\",\"dateModified\":\"2021-09-30T15:15:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/6efbef67fc52e8e1456e88c1d9e31185\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/Espectaculos1-30.09.21.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/Espectaculos1-30.09.21.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/30\\\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/6efbef67fc52e8e1456e88c1d9e31185\",\"name\":\"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50efe5915c3eac137dcc550ff1c590bc6054705eb482a33520c9501c8eec550f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50efe5915c3eac137dcc550ff1c590bc6054705eb482a33520c9501c8eec550f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50efe5915c3eac137dcc550ff1c590bc6054705eb482a33520c9501c8eec550f?s=96&d=mm&r=g\",\"caption\":\"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/maria\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional - LA BRAVA RADIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/","og_locale":"es_MX","og_type":"article","og_title":"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional - LA BRAVA RADIO","og_description":"Antequera, M\u00e1laga.- Una de las ciudades con mucho carisma en M\u00e1laga es Antequera donde su belleza arquitect\u00f3nica es parte de sus atractivos para visitarla, sin embargo tambi\u00e9n un pretexto es ir a escuchar \u00f3rganos hist\u00f3ricos que se encuentran en diferentes edificios. Jes\u00fas Sampedro, director del Festival Internacional de \u00d3rgano de Antequera, nos explic\u00f3 que el [&hellip;]","og_url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2021-09-30T15:15:39+00:00","article_modified_time":"2021-09-30T15:15:40+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/Espectaculos1-30.09.21.jpg","type":"image\/jpeg"}],"author":"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/"},"author":{"name":"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/6efbef67fc52e8e1456e88c1d9e31185"},"headline":"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional","datePublished":"2021-09-30T15:15:39+00:00","dateModified":"2021-09-30T15:15:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/"},"wordCount":591,"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/Espectaculos1-30.09.21.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/","name":"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/Espectaculos1-30.09.21.jpg","datePublished":"2021-09-30T15:15:39+00:00","dateModified":"2021-09-30T15:15:40+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/6efbef67fc52e8e1456e88c1d9e31185"},"breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/Espectaculos1-30.09.21.jpg","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/Espectaculos1-30.09.21.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/30\/antequera-la-ciudad-de-los-organos-historicos-presento-su-segundo-festival-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"Antequera, la ciudad de los \u00f3rganos hist\u00f3ricos present\u00f3 su Segundo Festival Internacional"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/6efbef67fc52e8e1456e88c1d9e31185","name":"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/50efe5915c3eac137dcc550ff1c590bc6054705eb482a33520c9501c8eec550f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50efe5915c3eac137dcc550ff1c590bc6054705eb482a33520c9501c8eec550f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50efe5915c3eac137dcc550ff1c590bc6054705eb482a33520c9501c8eec550f?s=96&d=mm&r=g","caption":"Mar\u00eda Esther Beltr\u00e1n Mart\u00ednez"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/maria\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=2840"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/2842"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=2840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=2840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=2840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}