{"id":2804,"date":"2021-09-29T19:31:17","date_gmt":"2021-09-30T00:31:17","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?p=2804"},"modified":"2021-09-29T19:31:19","modified_gmt":"2021-09-30T00:31:19","slug":"penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/","title":{"rendered":"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p>El lunes se inaugur\u00f3 una exposici\u00f3n en donde se exhiben diversas piezas que pertenecen a diferentes \u00e9pocas de la historia de M\u00e9xico, llamada <strong>\u201cLa Grandeza de M\u00e9xico\u201d<\/strong>. La inauguraci\u00f3n fue encabezada por el presidente<strong> Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO)<\/strong> y la titular de la <strong>Secretar\u00eda de Cultura, Alejandra Frausto<\/strong>, en el marco de la <strong>conmemoraci\u00f3n de los 200 a\u00f1os de la consumaci\u00f3n de la Independencia de M\u00e9xico.<\/strong><\/p>\n\n\n\n<p>Y es que durante el mandato del presidente <strong>L\u00f3pez Obrador<\/strong> se ha puesto especial ah\u00ednco en recuperar <strong>piezas hist\u00f3ricas<\/strong> que est\u00e1n repartidas al rededor del mundo. En lo que va del sexenio de L\u00f3pez Obrador, que son tres a\u00f1os, se han recuperado m\u00e1s de <strong>5,000 obras que estaban en diferentes pa\u00edses.<\/strong><\/p>\n\n\n\n<p>En la exposici\u00f3n se pueden ver diversas piezas hist\u00f3ricas, desde c\u00f3dices cedidos por el Vaticano a la llamada gobernanta huasteca, una escultura femenina del remoto primer milenio antes de Cristo, encontrada por el INAH a comienzos de este a\u00f1o en el territorio huasteco del estado de Veracruz. \u201cSe representa todo M\u00e9xico mostrando aqu\u00ed que la historia de este pa\u00eds no inici\u00f3 apenas hace 500 a\u00f1os\u201d, declar\u00f3 Frausto en la inauguraci\u00f3n.<\/p>\n\n\n\n<p>Sin embargo, hay algunas piezas que no se pudieron recuperar a pesar de buscar la forma de que fueran prestadas a la naci\u00f3n para su exposici\u00f3n. Tal es el caso del llamado <strong>Penacho de Moctezuma,<\/strong> que se encuentra en <strong>Viena, Austria.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.31.jpeg\" alt=\"\" class=\"wp-image-2806\" srcset=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.31.jpeg 768w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.31-300x200.jpeg 300w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.31-630x420.jpeg 630w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.31-640x427.jpeg 640w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.31-681x454.jpeg 681w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>En lo que va del sexenio del presidente L\u00f3pez Obrador, se han recuperado m\u00e1s de 5,000 piezas arqueol\u00f3gicas que estaban en otros pa\u00edses. FOTO: GALO CA\u00d1AS\/CUARTOSCURO.COM<\/figcaption><\/figure>\n\n\n\n<p>Fue justo hace poco menos de un a\u00f1o, en octubre de 2020, cuando la esposa del presidente<strong> Andr\u00e9s Manuel L\u00f3pez Obrador, Beatriz Guti\u00e9rrez M\u00fcller,<\/strong> que fue de visita a aquel pa\u00eds europeo, con la misi\u00f3n de que le prestaran la pieza prehisp\u00e1nica, la cual, no se sabe con exactitud c\u00f3mo lleg\u00f3 hasta all\u00e1.<\/p>\n\n\n\n<p>El presidente L\u00f3pez Obrador inform\u00f3 aquella ocasi\u00f3n, por medio de sus <strong>redes sociales, <\/strong>que hab\u00eda pedido a la tambi\u00e9n periodista y escritora que insistiera al presidente de<strong> Austria Alexander Van der Bellen,<\/strong> sobre el pr\u00e9stamo de la pieza, sin tener \u00e9xito.<\/p>\n\n\n\n<p>\u201cLe recomend\u00e9 que insistiera en el<strong> Penacho de Moctezuma<\/strong>, aunque se trata de una misi\u00f3n casi imposible, dado que se lo han apropiado por completo\u201d, inform\u00f3 el presidente L\u00f3pez Obrador a trav\u00e9s de redes sociales.<\/p>\n\n\n\n<p>En aquella ocasi\u00f3n, la esposa de <strong>AMLO <\/strong>se reuni\u00f3 con el presidente de <strong>Austria<\/strong>, con la finalidad de que la pieza hist\u00f3rica fuera prestada a M\u00e9xico para que fuera exhibida durante la exposici\u00f3n que recientemente se mont\u00f3. Sin embargo, la respuesta fue negativa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.32.jpg\" alt=\"\" class=\"wp-image-2807\" srcset=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.32.jpg 768w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.32-300x200.jpg 300w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.32-630x420.jpg 630w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.32-640x427.jpg 640w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.32-681x454.jpg 681w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>El Penacho de Moctezuma habr\u00eda pertenecido al emperador azteca. EFE\/Luis Lid\u00f3n\/Archivo<\/figcaption><\/figure>\n\n\n\n<p>A pesar de que el Penacho de Moctezuma es una pieza famosa, poco se sabe sobre ella. La pieza arqueol\u00f3gica e hist\u00f3rica, lleg\u00f3 a <strong>Austria <\/strong>en 1699 y permaneci\u00f3 ah\u00ed por m\u00e1s de 200 a\u00f1os, resguardado en el <strong>Palacio de Ambras.<\/strong> No se sabe la manera en la que lleg\u00f3 al pa\u00eds europeo, pero se sospecha que fue un regalo del tlatoani <strong>Moctezuma <\/strong>al conquistado espa\u00f1ol<strong> Hern\u00e1n Cort\u00e9s<\/strong>, y que al ser enviado a Espa\u00f1a por este \u00faltimo, el barco en el que viajaba fue saqueado por piratas, quienes lo extrajeron.<\/p>\n\n\n\n<p>En 1978 fue restaurado primera vez y ha sido renovado en diversas ocasiones.<\/p>\n\n\n\n<p>La pieza hist\u00f3rica est\u00e1 valuada en <strong>500 millones de d\u00f3lares<\/strong>, seg\u00fan el medio <em>Oink Oink<\/em>. La pieza est\u00e1 compuesta por<strong> 1,500 piezas y 222 plumas de distintas especies de aves<\/strong>. La estructura del penacho es de palillos de hilo de agave y algod\u00f3n, con refuerzos que generan una red del mismo hilo. Mide 1.16 metros de alto, y tiene 1.75 metros de ancho. Su precio se debe a estas caracter\u00edsticas, adem\u00e1s de su rareza y antig\u00fcedad.<\/p>\n\n\n\n<p>Actualmente, es exhibido en el <strong>Museo de Etnolog\u00eda de Viena<\/strong>, y en el pasado, el gobierno de M\u00e9xico lleg\u00f3 a un acuerdo con el gobierno de aquel pa\u00eds, para que los mexicanos con identificaci\u00f3n puedan entrar a verlo sin costo alguno.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021-32.webp\" alt=\"\" class=\"wp-image-2808\" srcset=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021-32.webp 768w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021-32-300x169.webp 300w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021-32-747x420.webp 747w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021-32-640x360.webp 640w, https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021-32-681x383.webp 681w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Beatriz Guti\u00e9rrez M\u00fcller lament\u00f3 la negativa de Austria a devolver penacho de Moctezuma (Foto: captura de pantalla)<\/figcaption><\/figure>\n\n\n\n<p>Una de las cosas por las que se ha negado que el<strong> Penacho de Moctezuma vuelva a M\u00e9xico, <\/strong>es por su fragilidad, pues debido a esta, las vibraciones de un barco o un avi\u00f3n podr\u00edan da\u00f1arlo de manera permanente.<\/p>\n\n\n\n<p>Ya anteriormente, en 2011, el gobierno del expresidente <strong>Felipe Calder\u00f3n <\/strong>intent\u00f3 negociar con Austria para que a cambio del <strong>Penacho de Moctezuma, ellos adquirieran la Carrosa del Emperador Maximiliano,<\/strong> sin embargo, la respuesta fue la misma: no, pues se puede da\u00f1ar de manera permanente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes se inaugur\u00f3 una exposici\u00f3n en donde se exhiben diversas piezas que pertenecen a diferentes \u00e9pocas de la historia de M\u00e9xico, llamada \u201cLa Grandeza de M\u00e9xico\u201d. La inauguraci\u00f3n fue encabezada por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO) y la titular de la Secretar\u00eda de Cultura, Alejandra Frausto, en el marco de la conmemoraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":{"0":"post-2804","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd - LA BRAVA RADIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"El lunes se inaugur\u00f3 una exposici\u00f3n en donde se exhiben diversas piezas que pertenecen a diferentes \u00e9pocas de la historia de M\u00e9xico, llamada \u201cLa Grandeza de M\u00e9xico\u201d. La inauguraci\u00f3n fue encabezada por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO) y la titular de la Secretar\u00eda de Cultura, Alejandra Frausto, en el marco de la conmemoraci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T00:31:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T00:31:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Infobae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Infobae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/\"},\"author\":{\"name\":\"Infobae\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/62224ae647a2d7c8bc75812c343c4433\"},\"headline\":\"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd\",\"datePublished\":\"2021-09-30T00:31:17+00:00\",\"dateModified\":\"2021-09-30T00:31:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/\"},\"wordCount\":847,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/nacional29092021.30.jpg\",\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/\",\"name\":\"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/nacional29092021.30.jpg\",\"datePublished\":\"2021-09-30T00:31:17+00:00\",\"dateModified\":\"2021-09-30T00:31:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/62224ae647a2d7c8bc75812c343c4433\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/nacional29092021.30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/nacional29092021.30.jpg\",\"width\":768,\"height\":512,\"caption\":\"El Penacho de Moctezuma es exhibido en el Museo de Etnolog\u00eda de Viena, Austria. (Foto: EFE)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/29\\\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/62224ae647a2d7c8bc75812c343c4433\",\"name\":\"Infobae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/516600970682560d6fbeb0f1663b27fb5fbe4ca00f4dc3eaa4a972bfc5485f05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/516600970682560d6fbeb0f1663b27fb5fbe4ca00f4dc3eaa4a972bfc5485f05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/516600970682560d6fbeb0f1663b27fb5fbe4ca00f4dc3eaa4a972bfc5485f05?s=96&d=mm&r=g\",\"caption\":\"Infobae\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/infobae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd - LA BRAVA RADIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/","og_locale":"es_MX","og_type":"article","og_title":"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd - LA BRAVA RADIO","og_description":"El lunes se inaugur\u00f3 una exposici\u00f3n en donde se exhiben diversas piezas que pertenecen a diferentes \u00e9pocas de la historia de M\u00e9xico, llamada \u201cLa Grandeza de M\u00e9xico\u201d. La inauguraci\u00f3n fue encabezada por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO) y la titular de la Secretar\u00eda de Cultura, Alejandra Frausto, en el marco de la conmemoraci\u00f3n [&hellip;]","og_url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2021-09-30T00:31:17+00:00","article_modified_time":"2021-09-30T00:31:19+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.30.jpg","type":"image\/jpeg"}],"author":"Infobae","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Infobae","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/"},"author":{"name":"Infobae","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/62224ae647a2d7c8bc75812c343c4433"},"headline":"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd","datePublished":"2021-09-30T00:31:17+00:00","dateModified":"2021-09-30T00:31:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/"},"wordCount":847,"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.30.jpg","articleSection":["NACIONAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/","name":"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.30.jpg","datePublished":"2021-09-30T00:31:17+00:00","dateModified":"2021-09-30T00:31:19+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/62224ae647a2d7c8bc75812c343c4433"},"breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.30.jpg","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/nacional29092021.30.jpg","width":768,"height":512,"caption":"El Penacho de Moctezuma es exhibido en el Museo de Etnolog\u00eda de Viena, Austria. (Foto: EFE)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/29\/penacho-de-moctezuma-el-tesoro-arqueologico-de-mexico-valuado-en-500-mdd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"Penacho de Moctezuma: el tesoro arqueol\u00f3gico de M\u00e9xico valuado en 500 mdd"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/62224ae647a2d7c8bc75812c343c4433","name":"Infobae","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/516600970682560d6fbeb0f1663b27fb5fbe4ca00f4dc3eaa4a972bfc5485f05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/516600970682560d6fbeb0f1663b27fb5fbe4ca00f4dc3eaa4a972bfc5485f05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/516600970682560d6fbeb0f1663b27fb5fbe4ca00f4dc3eaa4a972bfc5485f05?s=96&d=mm&r=g","caption":"Infobae"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/infobae\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=2804"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/2805"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=2804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=2804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=2804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}