{"id":2390,"date":"2021-09-23T12:38:31","date_gmt":"2021-09-23T17:38:31","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?p=2390"},"modified":"2021-09-23T12:38:32","modified_gmt":"2021-09-23T17:38:32","slug":"si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/","title":{"rendered":"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p>OAXACA, Oax.- El director del Hospital de la Ni\u00f1ez Oaxaque\u00f1a (HNO), Roberto Salvador Luna Cruz, inform\u00f3 que s\u00ed hay desabasto de medicamentos en este nosocomio.<\/p>\n\n\n\n<p>El secretario de salud federal, Jorge Alcocer, inform\u00f3 que hab\u00edan enviado a Oaxaca los medicamentos, incluidos los oncol\u00f3gicos.<\/p>\n\n\n\n<p>Sin embargo, Salvador Luna se\u00f1al\u00f3 que durante todo este 2021, ha sido el gobierno estatal quien ha dotado del medicamento.<\/p>\n\n\n\n<p>\u201cEl desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron\u201d.<\/p>\n\n\n\n<p>Expuso que el desabasto fue porque el Hospital es un organismo p\u00fablico descentralizado y el Instituto de Salud para el Bienestar (Insabi) no tiene la cobertura.<\/p>\n\n\n\n<p>\u201cNosotros lo solicitamos al Insabi, pero el Insabi nos manda con el gobierno del estado\u201d.<\/p>\n\n\n\n<p>Aunque refiri\u00f3 que este mi\u00e9rcoles hubo una reuni\u00f3n con el Insabi para revisar la forma en que pueden hacer llegar los medicamentos a trav\u00e9s del estado.<\/p>\n\n\n\n<p>El Hospital de la ni\u00f1ez atiende actualmente a 166 ni\u00f1os y ni\u00f1as y son 40 claves las que hacen falta para darles atenci\u00f3n.<\/p>\n\n\n\n<p>La complejidad de este hospital aument\u00f3 por el despido de personal especializado que atend\u00eda a las y los menores, situaci\u00f3n de la que tambi\u00e9n se deslind\u00f3 el Insabi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OAXACA, Oax.- El director del Hospital de la Ni\u00f1ez Oaxaque\u00f1a (HNO), Roberto Salvador Luna Cruz, inform\u00f3 que s\u00ed hay desabasto de medicamentos en este nosocomio. El secretario de salud federal, Jorge Alcocer, inform\u00f3 que hab\u00edan enviado a Oaxaca los medicamentos, incluidos los oncol\u00f3gicos. Sin embargo, Salvador Luna se\u00f1al\u00f3 que durante todo este 2021, ha sido [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-2390","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-oaxaca"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director - LA BRAVA RADIO<\/title>\n<meta name=\"description\" content=\"El desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"El desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-23T17:38:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-23T17:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local23092021-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1256\" \/>\n\t<meta property=\"og:image:height\" content=\"753\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Quadratin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Quadratin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/\"},\"author\":{\"name\":\"Quadratin\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/5d48e9d9c63a14b1b91b5747df612aa5\"},\"headline\":\"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director\",\"datePublished\":\"2021-09-23T17:38:31+00:00\",\"dateModified\":\"2021-09-23T17:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/\"},\"wordCount\":233,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local23092021-8.png\",\"articleSection\":[\"LOCAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/\",\"name\":\"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local23092021-8.png\",\"datePublished\":\"2021-09-23T17:38:31+00:00\",\"dateModified\":\"2021-09-23T17:38:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/5d48e9d9c63a14b1b91b5747df612aa5\"},\"description\":\"El desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local23092021-8.png\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/local23092021-8.png\",\"width\":1256,\"height\":753},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/23\\\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/5d48e9d9c63a14b1b91b5747df612aa5\",\"name\":\"Quadratin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34008d7d72488432d6a74f81e839efc9f754b118786ca32cf39d9d5508a68f63?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34008d7d72488432d6a74f81e839efc9f754b118786ca32cf39d9d5508a68f63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34008d7d72488432d6a74f81e839efc9f754b118786ca32cf39d9d5508a68f63?s=96&d=mm&r=g\",\"caption\":\"Quadratin\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/quadratin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director - LA BRAVA RADIO","description":"El desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director - LA BRAVA RADIO","og_description":"El desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron","og_url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2021-09-23T17:38:31+00:00","article_modified_time":"2021-09-23T17:38:32+00:00","og_image":[{"width":1256,"height":753,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local23092021-8.png","type":"image\/png"}],"author":"Quadratin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Quadratin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/"},"author":{"name":"Quadratin","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/5d48e9d9c63a14b1b91b5747df612aa5"},"headline":"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director","datePublished":"2021-09-23T17:38:31+00:00","dateModified":"2021-09-23T17:38:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/"},"wordCount":233,"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local23092021-8.png","articleSection":["LOCAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/","name":"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local23092021-8.png","datePublished":"2021-09-23T17:38:31+00:00","dateModified":"2021-09-23T17:38:32+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/5d48e9d9c63a14b1b91b5747df612aa5"},"description":"El desabasto es reciente, a principios de a\u00f1o el gobierno de Oaxaca y el DIF nos ha apoyado, sin embargo, ya no lo consideraron","breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local23092021-8.png","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/local23092021-8.png","width":1256,"height":753},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/23\/si-hay-desabasto-de-medicamentos-en-el-hospital-de-la-ninez-director\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"S\u00ed hay desabasto de medicamentos en el Hospital de la Ni\u00f1ez: director"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/5d48e9d9c63a14b1b91b5747df612aa5","name":"Quadratin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34008d7d72488432d6a74f81e839efc9f754b118786ca32cf39d9d5508a68f63?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34008d7d72488432d6a74f81e839efc9f754b118786ca32cf39d9d5508a68f63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34008d7d72488432d6a74f81e839efc9f754b118786ca32cf39d9d5508a68f63?s=96&d=mm&r=g","caption":"Quadratin"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/quadratin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=2390"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/2390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/2391"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=2390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=2390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=2390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}