{"id":1458,"date":"2021-09-08T18:24:24","date_gmt":"2021-09-08T23:24:24","guid":{"rendered":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?p=1458"},"modified":"2021-09-08T18:24:27","modified_gmt":"2021-09-08T23:24:27","slug":"ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes","status":"publish","type":"post","link":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/","title":{"rendered":"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax.-<\/strong> El combate frontal y continuo contra la delincuencia de que realiza la Fiscal\u00eda General del Estado de Oaxaca (FGEO), dio como resultado la aprehensi\u00f3n de la persona del sexo masculino identificado como E. F. M. R., quien es probable part\u00edcipe del delito de extorsi\u00f3n y asociaci\u00f3n delictuosa en perjuicio de un grupo de 19 comerciantes y productores de tomate establecidos en inmediaciones de la ex f\u00e1brica de triplay, ubicada en la periferia de la Ciudad de Oaxaca de Ju\u00e1rez.<\/p>\n\n\n\n<p>De acuerdo con la causa penal 675\/2021, entre el 30 de mayo y el 30 de junio de 2021, el imputado y otros sujetos -quienes integran una organizaci\u00f3n- mediante amenazas pretend\u00edan obligar a los comerciantes a pagar cuotas de dinero de manera mensual a cambio de permitirles vender sus productos en inmediaciones de la ex f\u00e1brica de triplay, ubicada en Oaxaca de Ju\u00e1rez.<\/p>\n\n\n\n<p>Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes -a trav\u00e9s de la Fiscal\u00eda Especializada en Atenci\u00f3n a Delitos de Alto Impacto-, logrando aprehender el pasado 7 de septiembre a uno de los probables responsables, quien fue presentado de forma inmediata ante el Juez de la causa.<\/p>\n\n\n\n<p>En audiencia, la defensa del imputado solicit\u00f3 el t\u00e9rmino constitucional, mismo que fenece el pr\u00f3ximo 10 de septiembre de 2021, quedando en tanto en prisi\u00f3n preventiva justificada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax.- El combate frontal y continuo contra la delincuencia de que realiza la Fiscal\u00eda General del Estado de Oaxaca (FGEO), dio como resultado la aprehensi\u00f3n de la persona del sexo masculino identificado como E. F. M. R., quien es probable part\u00edcipe del delito de extorsi\u00f3n y asociaci\u00f3n delictuosa en perjuicio de un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":{"0":"post-1458","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiaca"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes - LA BRAVA RADIO<\/title>\n<meta name=\"description\" content=\"Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes - LA BRAVA RADIO\" \/>\n<meta property=\"og:description\" content=\"Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/\" \/>\n<meta property=\"og:site_name\" content=\"LA BRAVA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-08T23:24:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-08T23:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/policiaca08092021-30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/\"},\"author\":{\"name\":\"Staff\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\"},\"headline\":\"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes\",\"datePublished\":\"2021-09-08T23:24:24+00:00\",\"dateModified\":\"2021-09-08T23:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/\"},\"wordCount\":255,\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/policiaca08092021-30.jpg\",\"articleSection\":[\"POLICIACA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/\",\"name\":\"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes - LA BRAVA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/policiaca08092021-30.jpg\",\"datePublished\":\"2021-09-08T23:24:24+00:00\",\"dateModified\":\"2021-09-08T23:24:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\"},\"description\":\"Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/policiaca08092021-30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/09\\\/policiaca08092021-30.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/2021\\\/09\\\/08\\\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#website\",\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/\",\"name\":\"LA BRAVA RADIO\",\"description\":\"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/#\\\/schema\\\/person\\\/c297800e17b4069897e910b03dcdcea7\",\"name\":\"Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g\",\"caption\":\"Staff\"},\"url\":\"https:\\\/\\\/www.bbmnoticias.com\\\/labravaradiofm\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes - LA BRAVA RADIO","description":"Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/","og_locale":"es_MX","og_type":"article","og_title":"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes - LA BRAVA RADIO","og_description":"Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes","og_url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/","og_site_name":"LA BRAVA RADIO","article_published_time":"2021-09-08T23:24:24+00:00","article_modified_time":"2021-09-08T23:24:27+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/policiaca08092021-30.jpg","type":"image\/jpeg"}],"author":"Staff","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Staff","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#article","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/"},"author":{"name":"Staff","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7"},"headline":"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes","datePublished":"2021-09-08T23:24:24+00:00","dateModified":"2021-09-08T23:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/"},"wordCount":255,"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/policiaca08092021-30.jpg","articleSection":["POLICIACA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/","name":"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes - LA BRAVA RADIO","isPartOf":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#primaryimage"},"image":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/policiaca08092021-30.jpg","datePublished":"2021-09-08T23:24:24+00:00","dateModified":"2021-09-08T23:24:27+00:00","author":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7"},"description":"Ante este hecho y tras la denuncia presentada, la Instituci\u00f3n de procuraci\u00f3n de justicia inici\u00f3 las investigaciones correspondientes","breadcrumb":{"@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#primaryimage","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/policiaca08092021-30.jpg","contentUrl":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-content\/uploads\/sites\/5\/2021\/09\/policiaca08092021-30.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/2021\/09\/08\/ejecuta-fgeo-orden-de-aprehension-contra-sujeto-que-probablemente-extorsionaba-a-comerciantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/"},{"@type":"ListItem","position":2,"name":"Ejecuta FGEO orden de aprehensi\u00f3n contra sujeto que probablemente extorsionaba a comerciantes"}]},{"@type":"WebSite","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#website","url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/","name":"LA BRAVA RADIO","description":"Empresa productora de medios, Radiodifusi\u00f3n, Noticias, tendencias y todo lo que necesitas saber de la pol\u00edtica mexicana e internacional; entretenimiento, espect\u00e1culos, salud y mucho m\u00e1s.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/#\/schema\/person\/c297800e17b4069897e910b03dcdcea7","name":"Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd21ad66fd8b98c407f9dee5b5e588cfe7f0d8579ec20fa6527cd59bab7f0f0?s=96&d=mm&r=g","caption":"Staff"},"url":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/1458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/comments?post=1458"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/posts\/1458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media\/1459"}],"wp:attachment":[{"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/media?parent=1458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/categories?post=1458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmnoticias.com\/labravaradiofm\/wp-json\/wp\/v2\/tags?post=1458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}